{"id":4074,"date":"2026-05-04T02:25:49","date_gmt":"2026-05-04T00:25:49","guid":{"rendered":"https:\/\/tuskwood.com\/produkt\/tuskwood-akvarierot-akta-uraldrig-bogwood-unik-70-cm-p092618\/"},"modified":"2026-05-11T18:51:32","modified_gmt":"2026-05-11T16:51:32","slug":"tuskwood-akvarierot-akta-uraldrig-bogwood-unik-70-cm-p092618","status":"publish","type":"product","link":"https:\/\/tuskwood.com\/fr\/produkt\/tuskwood-akvarierot-akta-uraldrig-bogwood-unik-70-cm-p092618\/","title":{"rendered":"Tuskwood Akvarierot WYSIWYG \u00c4kta Bogwood Unik 70 cm P092618"},"content":{"rendered":"<h2>Unik produkt P092618<\/h2>\n<p>Une pi\u00e8ce unique de bois de tourbi\u00e8re scandinave, naturellement conserv\u00e9e dans la tourbe pendant des centaines, voire des milliers d'ann\u00e9es. Cette pi\u00e8ce attire tous les regards et convient parfaitement comme racine d'aquarium dans les paysages et les aquariums.<\/p>\n<p><strong>Il s'agit d'une racine unique, et c'est exactement la racine de la photo que vous achetez.<\/strong> Ce que vous voyez est ce que vous obtenez, WYSIWYG.<\/p>\n<h3>Description de la nature de la racine<\/h3>\n<p>Denna unika Tuskwood rot har en distinkt b\u00f6jd bas som \u00f6verg\u00e5r i flera upp\u00e5tstr\u00e4vande grenar och finare rotdelar. Med sina m\u00e5tt p\u00e5 70 cm l\u00e4ngd, 20 cm djup och 55 cm h\u00f6jd erbjuder den en imponerande vertikal och horisontell struktur. Dess naturliga, v\u00e4derbitna utseende skapar en omedelbar k\u00e4nsla av \u00e5lder och karakt\u00e4r i akvariet.<\/p>\n<h3>Suggestions de style d'aquarium et id\u00e9es de plantation<\/h3>\n<p>Roten passar utm\u00e4rkt f\u00f6r naturinspirerade akvarier, djungelstilar eller biotoper som efterliknar en b\u00e4ckmilj\u00f6. F\u00e4st enkelt v\u00e4xter som Anubias, Bucephalandra, Javaormbunke och olika mossor p\u00e5 grenarna f\u00f6r en frodig effekt. F\u00f6r den mer avancerade akvaristen kan den kombineras med markt\u00e4ckare som Monte Carlo eller Eleocharis i f\u00f6rgrunden, och bakgrundsv\u00e4xter som Rotala f\u00f6r att skapa djup.<\/p>\n<h3>Dimensions de la racine<\/h3>\n<ul>\n<li><strong>Longueur :<\/strong> 70cm<\/li>\n<li><strong>Hauteur :<\/strong> 55cm<\/li>\n<li><strong>Profondeur :<\/strong> 20 cm (8 in)<\/li>\n<\/ul>\n<h3>Format et taille de l'aquarium propos\u00e9s<\/h3>\n<p>Denna rot \u00e4r idealisk f\u00f6r akvarier som \u00e4r 80 cm eller l\u00e4ngre, s\u00e4rskilt rektangul\u00e4ra modeller. Dess storlek och form fyller ut utrymmet v\u00e4l och blir en central del i ett medelstort till stort akvarium.<\/p>\n<h3>Avantages de Tuskwood<\/h3>\n<ul>\n<li>V\u00e9ritable bois de tourbi\u00e8re \/ bois de mousse min\u00e9ralis\u00e9<\/li>\n<li>Longue dur\u00e9e de vie<\/li>\n<li>Normalement pas de formation de biofilm ou de mucus<\/li>\n<li>Fonctionne aussi bien en eau dure qu'en eau douce<\/li>\n<li>Capacit\u00e9 d'enfoncement fiable, enfoncement normal en 2 \u00e0 4 semaines<\/li>\n<li>La couleur naturellement belle se d\u00e9cline en brun fonc\u00e9 avec une l\u00e9g\u00e8re teinte rouge\u00e2tre sous l'eau.<\/li>\n<\/ul>\n<p>Contrairement au bois d'araign\u00e9e, au manzanita, au pal\u00e9tuvier ou au bois flott\u00e9 de Malaisie, le Tuskwood provient d'Europe et s'est form\u00e9 naturellement dans les tourbi\u00e8res nordiques. La min\u00e9ralisation et l'impr\u00e9gnation d'humus rendent le bois durable et beau.<\/p>\n<p>Tuskwood lib\u00e8re lentement des substances humiques naturelles qui favorisent la sant\u00e9 des poissons. Cependant, l'impact sur la couleur de l'eau est minime et g\u00e9n\u00e9ralement imperceptible.<\/p>\n<ul>\n<li>Lib\u00e9ration stable et douce de l'humus<\/li>\n<li>Positif pour le bien-\u00eatre des poissons<\/li>\n<li>Antimicrobien pour la rate<\/li>\n<\/ul>\n<h3>Un choix plus durable<\/h3>\n<p>Une grande partie du bois vendu pour l'aquascaping provient des for\u00eats tropicales d'Asie et est exp\u00e9di\u00e9 \u00e0 l'autre bout du monde.<\/p>\n<p>Tuskwood est un mat\u00e9riau naturel nordique, collect\u00e9 localement en tant que sous-produit d'autres utilisations naturelles. Cela en fait un choix plus durable, sans exploitation foresti\u00e8re tropicale non r\u00e9glement\u00e9e, sans destruction de la mangrove et sans conditions de travail indignes. Tuskwood est synonyme de transport minimal et de promotion de l'\u00e9conomie et des emplois locaux.<\/p>\n<p><em>Tuskwood est une tr\u00e8s petite entreprise et nous utilisons l'IA pour nous concentrer sur la qualit\u00e9 et la livraison. Les rendus de Aquascape, la traduction dans des langues autres que le su\u00e9dois et la description de la racine individuelle sur cette page sont r\u00e9alis\u00e9s \u00e0 l'aide de l'IA et peuvent comporter des erreurs mineures. Nous nous en excusons. De vraies personnes sont toujours disponibles par t\u00e9l\u00e9phone ou par courrier \u00e9lectronique.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<h3>Tuskwood Bois de tourbi\u00e8re ancien<\/h3>\n<p>V\u00e9ritable bois de tourbi\u00e8re, cueilli \u00e0 la main dans les tourbi\u00e8res nordiques o\u00f9 il a \u00e9t\u00e9 naturellement pr\u00e9serv\u00e9 pendant 500 \u00e0 4000 ans. Ce processus unique rend le bois partiellement min\u00e9ralis\u00e9, impr\u00e9gn\u00e9 de substances humiques, durable et d'une magnifique couleur brun rouge\u00e2tre fonc\u00e9. Tuskwood Ancient Bogwood est un type de racine tr\u00e8s recherch\u00e9 pour les aquariums et l'aquascaping.<\/p>\n<ul>\n<li><strong>Longue dur\u00e9e de vie :<\/strong> Partiellement min\u00e9ralis\u00e9e et extr\u00eamement durable.<\/li>\n<li><strong>Positif pour l'environnement aquatique :<\/strong> Favorise l'\u00e9quilibre et la sant\u00e9 dans l'aquarium.<\/li>\n<li><strong>Pas de biofilm :<\/strong> Ne forme normalement pas de boue sur le bois.<\/li>\n<li><strong>Durable et produit localement :<\/strong> S\u00e9lectionn\u00e9s avec soin dans les pays nordiques.<\/li>\n<li><strong>Eau claire :<\/strong> L'impact du bois sur la couleur de l'eau est normalement tr\u00e8s limit\u00e9 et de courte dur\u00e9e.<\/li>\n<\/ul>","protected":false},"featured_media":4065,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[46],"product_cat":[254],"product_tag":[],"class_list":{"0":"post-4074","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tuskwood","7":"product_cat-tuskwood_bogwood_wysiwyg","8":"desktop-align-left","9":"tablet-align-left","10":"mobile-align-left","11":"ast-product-gallery-layout-vertical-slider","12":"ast-product-tabs-layout-accordion","14":"first","15":"instock","16":"sold-individually","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"shsp-ext":{"main":{},"variations":[]},"uagb_featured_image_src":{"full":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3.jpg",1024,1024,false],"thumbnail":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-150x150.jpg",150,150,true],"medium":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-300x300.jpg",300,300,true],"medium_large":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-768x768.jpg",768,768,true],"large":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3.jpg",1024,1024,false],"1536x1536":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3.jpg",1024,1024,false],"2048x2048":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3.jpg",1024,1024,false],"trp-custom-language-flag":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-400x400.jpg",400,400,true],"woocommerce_single":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3.jpg",1024,1024,false],"woocommerce_gallery_thumbnail":["https:\/\/tuskwood.com\/wp-content\/uploads\/2026\/05\/P092618-collage-aquascape01-measurement-thumb-3-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Codex Agent","author_link":"https:\/\/tuskwood.com\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Tuskwood Ancient Bogwood\u00c4kta bogwood, handplockat ur nordiska torvmossar d\u00e4r det konserverats naturligt i 500-4000 \u00e5r. Denna unika process g\u00f6r tr\u00e4et delvis mineraliserat, impregnerat med humus\u00e4mnen, h\u00e5llbart och vackert m\u00f6rkt r\u00f6dbrunt f\u00e4rgat. Tuskwood Ancient Bogwood \u00e4r en mycket eftertraktad typ av rot till akvarium och aquascaping.L\u00e5ng livsl\u00e4ngd: Delvis mineraliserat och extremt h\u00e5llbart.Positivt f\u00f6r vattenmilj\u00f6n: Fr\u00e4mjar balans\u2026","_links":{"self":[{"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/product\/4074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/comments?post=4074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/media\/4065"}],"wp:attachment":[{"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/media?parent=4074"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/product_brand?post=4074"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/product_cat?post=4074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tuskwood.com\/fr\/wp-json\/wp\/v2\/product_tag?post=4074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}